{"id":5116,"date":"2024-09-15T17:30:35","date_gmt":"2024-09-15T15:30:35","guid":{"rendered":"https:\/\/spuehler.legal\/politica-de-privacidad\/"},"modified":"2024-09-15T17:30:37","modified_gmt":"2024-09-15T15:30:37","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"&#13;\n<h1>Datenschutzerkl\u00e4rung<\/h1>&#13;\n<p>Procesamos datos personales (datos que identifican directa o indirectamente a personas f\u00edsicas) que recibimos de usted o de terceros implicados como parte de la relaci\u00f3n con el cliente o que recopilamos nosotros mismos. Sp\u00fchler Rechtsanw\u00e4lte AG es responsable del tratamiento de los datos personales descritos en la presente pol\u00edtica de privacidad.<\/p>&#13;\n&#13;\n<p>Usted mismo o las personas afectadas nos facilitan algunos de los datos personales cuando se ponen en contacto con nosotros por correo electr\u00f3nico o tel\u00e9fono y preguntan por nuestros servicios. Esto incluye, por ejemplo, el nombre y los datos de contacto, as\u00ed como informaci\u00f3n sobre la funci\u00f3n del interesado en la empresa u organizaci\u00f3n para la que usted o las respectivas personas de contacto trabajan o en cuyo nombre usted o ellas se ponen en contacto con nosotros. Tambi\u00e9n tratamos los datos personales que recibimos en nuestra correspondencia con terceros (es decir, clientes, contrapartes, autoridades y tribunales y sus empleados u otras personas de contacto) como parte de la relaci\u00f3n con el cliente (por ejemplo, nombre, datos de contacto, fecha de nacimiento, detalles del empleo, situaci\u00f3n econ\u00f3mica, circunstancias familiares o estado de salud). Tambi\u00e9n recopilamos algunos datos personales nosotros mismos, por ejemplo, de registros p\u00fablicos o p\u00e1ginas web.<br\/>Tratamos los tipos de datos personales antes mencionados principalmente para prestar, documentar y facturar nuestros servicios jur\u00eddicos.<\/p>&#13;\n&#13;\n<p>Para cumplir los fines descritos en la presente Pol\u00edtica de Privacidad, puede ser necesario que revelemos datos personales a las siguientes categor\u00edas de destinatarios: Proveedores de servicios externos, clientes, contrapartes y sus representantes legales, socios comerciales con los que podamos necesitar coordinar la prestaci\u00f3n de servicios jur\u00eddicos, as\u00ed como autoridades y tribunales.<\/p>&#13;\n&#13;\n<p>Procesamos los datos personales en nuestra \u00e1rea de responsabilidad en Suiza. Sin embargo, podemos transferir los datos personales a destinatarios (a saber, clientes, contrapartes o autoridades) que a su vez procesan los datos personales en otros pa\u00edses, incluidos aquellos que no garantizan un nivel de protecci\u00f3n de datos comparable al de la legislaci\u00f3n suiza. Haremos esto \u00faltimo bas\u00e1ndonos en el consentimiento o en cl\u00e1usulas contractuales est\u00e1ndar, o si es necesario para el cumplimiento de un contrato o la ejecuci\u00f3n de reclamaciones legales.<\/p>&#13;\n&#13;\n<p>S\u00f3lo almacenamos los datos personales durante el tiempo que sea necesario para procesar la relaci\u00f3n con el cliente, mientras exista una obligaci\u00f3n legal de conservar y documentar los datos o mientras tengamos un inter\u00e9s p\u00fablico o privado superior para hacerlo. Tomamos precauciones proporcionadas y razonables para proteger los datos personales de p\u00e9rdidas, modificaciones no autorizadas o accesos no autorizados por parte de terceros. Si nos facilita datos personales a trav\u00e9s de terceros (por ejemplo, a trav\u00e9s de sus empleados u otras personas de contacto), es usted quien debe informarles de forma general sobre el tratamiento por parte de proveedores de servicios legales (como nosotros) u otros proveedores de servicios externos (por ejemplo, en una declaraci\u00f3n de protecci\u00f3n de datos para empleados).<\/p>&#13;\n&#13;\n<p>Nos gustar\u00eda se\u00f1alar que utilizamos proveedores externos de servicios inform\u00e1ticos y proveedores de nube con servidores en Suiza como parte de la gesti\u00f3n de nuestro mandato. A continuaci\u00f3n, utilizamos determinados servicios inform\u00e1ticos y medios de comunicaci\u00f3n que pueden estar asociados a riesgos para la seguridad de los datos (por ejemplo, correo electr\u00f3nico, videoconferencia). Es su responsabilidad informarnos de cualquier medida de seguridad especial que desee adoptar.<\/p>&#13;\n&#13;\n<p>Tenemos un inter\u00e9s leg\u00edtimo en el tratamiento de los datos personales para los fines indicados. Parte del tratamiento tambi\u00e9n es necesario para que podamos cumplir nuestras obligaciones contractuales con usted o nuestras obligaciones legales (por ejemplo, obligaciones de conservaci\u00f3n).<\/p>&#13;\n&#13;\n<p>En particular, los interesados tienen derecho a recibir informaci\u00f3n sobre los datos personales almacenados sobre ellos y la finalidad del tratamiento de datos, derecho a la rectificaci\u00f3n y supresi\u00f3n o limitaci\u00f3n del tratamiento de sus datos personales, derecho a oponerse al tratamiento, derecho a interponer un recurso judicial ante una autoridad de control competente y derecho a la portabilidad de los datos. No obstante, tenga en cuenta que estos derechos est\u00e1n sujetos a condiciones y excepciones. En la medida en que lo permita o lo exija la ley, podremos rechazar las solicitudes de ejercicio de estos derechos. Por ejemplo, podemos o debemos conservar o seguir tratando los datos personales a pesar de una solicitud de supresi\u00f3n de los datos personales o de restricci\u00f3n del tratamiento por motivos legales.<br\/>No se requiere el consentimiento del cliente, sus empleados u otras personas de contacto para la pol\u00edtica de privacidad. La declaraci\u00f3n de protecci\u00f3n de datos se limita a informar sobre el tipo, el alcance y la finalidad del uso de los datos personales por parte de Sp\u00fchler Rechtsanw\u00e4lte AG. Sp\u00fchler Rechtsanw\u00e4lte AG se reserva el derecho a modificar unilateralmente, en cualquier momento y sin previo aviso, el contenido de la mencionada pol\u00edtica de privacidad. Por ello, le recomendamos que consulte regularmente la pol\u00edtica de privacidad de Sp\u00fchler Rechtsanw\u00e4lte AG en nuestra p\u00e1gina web.<\/p>&#13;\n&#13;\n<p>Si tiene alguna pregunta o si usted o sus empleados u otras personas de contacto desean ejercer sus derechos de protecci\u00f3n de datos, p\u00f3ngase en contacto con nosotros en info@spuehler.legal o escriba a Sp\u00fchler Rechtsanw\u00e4lte AG, General-Wille-Strasse 19, CH-8002 Z\u00farich, Suiza.<\/p>&#13;\n&#13;\n<p><strong>Suplemento a la pol\u00edtica de privacidad en relaci\u00f3n con el uso de este sitio web<\/strong><\/p>&#13;\n&#13;\n<p>Normalmente utilizamos \u00abcookies\u00bb y tecnolog\u00edas similares en nuestros sitios web para identificar su navegador o dispositivo. Una cookie es un peque\u00f1o archivo que se env\u00eda a su ordenador o se almacena autom\u00e1ticamente en su ordenador o dispositivo m\u00f3vil mediante el navegador web que utiliza cuando visita nuestro sitio web. Si vuelve a visitar este sitio web, podremos reconocerle, aunque no sepamos qui\u00e9n es usted. Adem\u00e1s de las cookies que s\u00f3lo se utilizan durante una sesi\u00f3n y se eliminan despu\u00e9s de su visita al sitio web (\u00abcookies de sesi\u00f3n\u00bb), las cookies tambi\u00e9n se pueden utilizar para almacenar la configuraci\u00f3n del usuario y otra informaci\u00f3n durante un cierto per\u00edodo de tiempo (por ejemplo, dos a\u00f1os) (\u00abcookies permanentes\u00bb). No obstante, puede configurar su navegador para que rechace las cookies, las guarde s\u00f3lo para una sesi\u00f3n o las elimine prematuramente. La mayor\u00eda de los navegadores est\u00e1n preconfigurados para aceptar cookies. Utilizamos cookies permanentes para poder guardar los ajustes de usuario (por ejemplo, idioma, autologin). Si bloquea las cookies, es posible que algunas funcionalidades (como la marcaci\u00f3n por idioma) dejen de funcionar. Al utilizar nuestros sitios web, usted acepta el uso de estas tecnolog\u00edas. Si no lo desea, deber\u00e1 configurar su navegador en consecuencia.<\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; Datenschutzerkl\u00e4rung &#13; Procesamos datos personales (datos que identifican directa o indirectamente a personas f\u00edsicas) que recibimos de usted o de terceros implicados como parte de la relaci\u00f3n con el cliente o que recopilamos nosotros mismos. Sp\u00fchler Rechtsanw\u00e4lte AG es responsable del tratamiento de los datos personales descritos en la presente pol\u00edtica de privacidad. &#13;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5116","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00edtica de privacidad - Sp\u00fchler Rechtsanw\u00e4lte AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad\" \/>\n<meta property=\"og:description\" content=\"&#013; Datenschutzerkl\u00e4rung &#013; Procesamos datos personales (datos que identifican directa o indirectamente a personas f\u00edsicas) que recibimos de usted o de terceros implicados como parte de la relaci\u00f3n con el cliente o que recopilamos nosotros mismos. Sp\u00fchler Rechtsanw\u00e4lte AG es responsable del tratamiento de los datos personales descritos en la presente pol\u00edtica de privacidad. &#013;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Sp\u00fchler Rechtsanw\u00e4lte AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/spuehler.legal\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-15T15:30:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/politica-de-privacidad\\\/\",\"url\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/politica-de-privacidad\\\/\",\"name\":\"Pol\u00edtica de privacidad - Sp\u00fchler Rechtsanw\u00e4lte AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#website\"},\"datePublished\":\"2024-09-15T15:30:35+00:00\",\"dateModified\":\"2024-09-15T15:30:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spuehler.legal\\\/es\\\/politica-de-privacidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/politica-de-privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/\",\"name\":\"Sp\u00fchler Rechtsanw\u00e4lte AG\",\"description\":\"Rechtsberatung und Rechtsvertretung in allen Lebenslagen\",\"publisher\":{\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#organization\",\"name\":\"Sp\u00fchler Rechtsanw\u00e4lte AG\",\"url\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spuehler.legal\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-spuehler-rechtsanwaelte.png\",\"contentUrl\":\"https:\\\/\\\/spuehler.legal\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-spuehler-rechtsanwaelte.png\",\"width\":898,\"height\":259,\"caption\":\"Sp\u00fchler Rechtsanw\u00e4lte AG\"},\"image\":{\"@id\":\"https:\\\/\\\/spuehler.legal\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/spuehler.legal\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fspuehler\\\/\"],\"description\":\"Die Anwaltskanzlei Sp\u00fchler Rechtsanw\u00e4lte AG ist beratend und prozessierend t\u00e4tig. Sie vertritt Privatpersonen sowie kleine und mittlere Unternehmen (KMU) in nationalen und internationalen Sachverhalten. Durch die breite Ausrichtung der Kanzlei ist eine ganzheitliche Beratung m\u00f6glich, welche auf Deutsch, Englisch, Spanisch, Franz\u00f6sisch, Italienisch oder Portugiesisch stattfindet. Kontaktieren Sie Ihre Anw\u00e4ltin oder Ihren Anwalt in Z\u00fcrich!\",\"email\":\"info@spuehler.legal\",\"telephone\":\"+41433440505\",\"legalName\":\"Sp\u00fchler Rechtsanw\u00e4lte AG\",\"foundingDate\":\"2018-01-01\",\"vatID\":\"CHE-431.484.624\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Sp\u00fchler Rechtsanw\u00e4lte AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad","og_description":"&#13; Datenschutzerkl\u00e4rung &#13; Procesamos datos personales (datos que identifican directa o indirectamente a personas f\u00edsicas) que recibimos de usted o de terceros implicados como parte de la relaci\u00f3n con el cliente o que recopilamos nosotros mismos. Sp\u00fchler Rechtsanw\u00e4lte AG es responsable del tratamiento de los datos personales descritos en la presente pol\u00edtica de privacidad. &#13;...","og_url":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/","og_site_name":"Sp\u00fchler Rechtsanw\u00e4lte AG","article_publisher":"https:\/\/www.facebook.com\/spuehler.legal","article_modified_time":"2024-09-15T15:30:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/","url":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad - Sp\u00fchler Rechtsanw\u00e4lte AG","isPartOf":{"@id":"https:\/\/spuehler.legal\/es\/#website"},"datePublished":"2024-09-15T15:30:35+00:00","dateModified":"2024-09-15T15:30:37+00:00","breadcrumb":{"@id":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spuehler.legal\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spuehler.legal\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/spuehler.legal\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/spuehler.legal\/es\/#website","url":"https:\/\/spuehler.legal\/es\/","name":"Sp\u00fchler Rechtsanw\u00e4lte AG","description":"Rechtsberatung und Rechtsvertretung in allen Lebenslagen","publisher":{"@id":"https:\/\/spuehler.legal\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spuehler.legal\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spuehler.legal\/es\/#organization","name":"Sp\u00fchler Rechtsanw\u00e4lte AG","url":"https:\/\/spuehler.legal\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spuehler.legal\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spuehler.legal\/wp-content\/uploads\/2020\/08\/logo-spuehler-rechtsanwaelte.png","contentUrl":"https:\/\/spuehler.legal\/wp-content\/uploads\/2020\/08\/logo-spuehler-rechtsanwaelte.png","width":898,"height":259,"caption":"Sp\u00fchler Rechtsanw\u00e4lte AG"},"image":{"@id":"https:\/\/spuehler.legal\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/spuehler.legal","https:\/\/www.linkedin.com\/in\/fspuehler\/"],"description":"Die Anwaltskanzlei Sp\u00fchler Rechtsanw\u00e4lte AG ist beratend und prozessierend t\u00e4tig. Sie vertritt Privatpersonen sowie kleine und mittlere Unternehmen (KMU) in nationalen und internationalen Sachverhalten. Durch die breite Ausrichtung der Kanzlei ist eine ganzheitliche Beratung m\u00f6glich, welche auf Deutsch, Englisch, Spanisch, Franz\u00f6sisch, Italienisch oder Portugiesisch stattfindet. Kontaktieren Sie Ihre Anw\u00e4ltin oder Ihren Anwalt in Z\u00fcrich!","email":"info@spuehler.legal","telephone":"+41433440505","legalName":"Sp\u00fchler Rechtsanw\u00e4lte AG","foundingDate":"2018-01-01","vatID":"CHE-431.484.624","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/pages\/5116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/comments?post=5116"}],"version-history":[{"count":1,"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/pages\/5116\/revisions"}],"predecessor-version":[{"id":5117,"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/pages\/5116\/revisions\/5117"}],"wp:attachment":[{"href":"https:\/\/spuehler.legal\/es\/wp-json\/wp\/v2\/media?parent=5116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}